{"id":2797,"date":"2020-04-26T08:59:50","date_gmt":"2020-04-26T11:59:50","guid":{"rendered":"https:\/\/dulcilandia.com.ar\/producto\/oblea-oblita-frutilla-135g\/"},"modified":"2026-09-02T04:26:07","modified_gmt":"2026-09-02T07:26:07","slug":"oblea-oblita-frutilla-135g","status":"publish","type":"product","link":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/","title":{"rendered":"OBLEA OBLITA FRUTILLA 135g"},"content":{"rendered":"<p>Cod: 07001412<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cod: 07001412<\/p>\n","protected":false},"featured_media":7128,"template":"","meta":[],"woo-feed-brand":[],"product_cat":[149],"product_tag":[],"bundle_layout":"","bundled_by":[],"bundled_items":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe\" \/>\n<meta property=\"og:description\" content=\"Cod: 07001412\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/\" \/>\n<meta property=\"og:site_name\" content=\"Dulcilandia Santa Fe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T07:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dulcilandia.com.ar\/wp-content\/uploads\/2020\/04\/07001412.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/#website\",\"url\":\"https:\/\/dulcilandia.com.ar\/sfe\/\",\"name\":\"Dulcilandia Santa Fe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dulcilandia.com.ar\/sfe\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/dulcilandia.com.ar\/sfe\/wp-content\/uploads\/sites\/3\/2020\/04\/07001412.png\",\"contentUrl\":\"https:\/\/dulcilandia.com.ar\/sfe\/wp-content\/uploads\/sites\/3\/2020\/04\/07001412.png\",\"width\":600,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#webpage\",\"url\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/\",\"name\":\"OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe\",\"isPartOf\":{\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#primaryimage\"},\"datePublished\":\"2020-04-26T11:59:50+00:00\",\"dateModified\":\"2026-09-02T07:26:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dulcilandia.com.ar\/sfe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/dulcilandia.com.ar\/sfe\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OBLEA OBLITA FRUTILLA 135g\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/","og_locale":"es_ES","og_type":"article","og_title":"OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe","og_description":"Cod: 07001412","og_url":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/","og_site_name":"Dulcilandia Santa Fe","article_modified_time":"2026-09-02T07:26:07+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/dulcilandia.com.ar\/wp-content\/uploads\/2020\/04\/07001412.png","path":"\/home\/c1331656\/public_html\/wp-content\/uploads\/2020\/04\/07001412.png","size":"full","id":7128,"alt":"","pixels":360000,"type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dulcilandia.com.ar\/sfe\/#website","url":"https:\/\/dulcilandia.com.ar\/sfe\/","name":"Dulcilandia Santa Fe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dulcilandia.com.ar\/sfe\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#primaryimage","inLanguage":"es","url":"https:\/\/dulcilandia.com.ar\/sfe\/wp-content\/uploads\/sites\/3\/2020\/04\/07001412.png","contentUrl":"https:\/\/dulcilandia.com.ar\/sfe\/wp-content\/uploads\/sites\/3\/2020\/04\/07001412.png","width":600,"height":600},{"@type":"WebPage","@id":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#webpage","url":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/","name":"OBLEA OBLITA FRUTILLA 135g - Dulcilandia Santa Fe","isPartOf":{"@id":"https:\/\/dulcilandia.com.ar\/sfe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#primaryimage"},"datePublished":"2020-04-26T11:59:50+00:00","dateModified":"2026-09-02T07:26:07+00:00","breadcrumb":{"@id":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dulcilandia.com.ar\/sfe\/producto\/oblea-oblita-frutilla-135g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dulcilandia.com.ar\/sfe\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dulcilandia.com.ar\/sfe\/shop\/"},{"@type":"ListItem","position":3,"name":"OBLEA OBLITA FRUTILLA 135g"}]}]}},"_links":{"self":[{"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/product\/2797"}],"collection":[{"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/media\/7128"}],"wp:attachment":[{"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/woo-feed-brand?post=2797"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/product_cat?post=2797"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dulcilandia.com.ar\/sfe\/wp-json\/wp\/v2\/product_tag?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}